{"id":5359,"date":"2021-05-30T20:38:00","date_gmt":"2021-05-30T20:38:00","guid":{"rendered":"https:\/\/2024.hpac.ca\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/"},"modified":"2026-03-11T12:36:42","modified_gmt":"2026-03-11T12:36:42","slug":"2021-recompenses-pour-les-pilotes-speciaux","status":"publish","type":"post","link":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/","title":{"rendered":"2021 r\u00e9compenses pour les pilotes \u00ab\u00a0sp\u00e9ciaux"},"content":{"rendered":"<p>[et_pb_section][et_pb_row][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text]<\/p>\n\r\n<!--more-->\r\n<p><strong>Instructeur de l&rsquo;ann\u00e9e<\/strong><\/p>\n<\/p>\n<p><center><img decoding=\"async\" style=\"width: 100%; max-width: 700px;\" src=\"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg\"><br \/>Dave Underwood (\u00e0 gauche) et Randy Rauck (\u00e0 droite), instructeur HG et propri\u00e9taire du Freedom Flight Park \u00e0 Lumby, en Colombie-Britannique.<\/center><\/p>\n<p><strong>Prix Solid Ground<\/strong><\/p>\n<ol>\n<li>Jerry Mason pour son travail sur les implications des drones pour le sport<br \/><center><img decoding=\"async\" style=\"width: 100%; max-width: 700px;\" src=\"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/jerry-mason-2021-scaled-e1622402799271.jpg\">\n<\/p>\n<p>Le laur\u00e9at Jerry Mason au centre, avec Edmond Rivere \u00e0 gauche et Norm Krcmar, instructeur et propri\u00e9taire de Paraglide Canada \u00e0 droite.<\/p>\n<\/p>\n<p><\/center><\/li>\n<li><center>Peter<\/center> Graf pour l&rsquo;enqu\u00eate m\u00e9dico-l\u00e9gale sur les accidents<center><img decoding=\"async\" style=\"width: 100%; max-width: 700px;\" src=\"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Peter-Graf-Award.jpg\"><br \/>Le laur\u00e9at Peter Graf (au milieu), James Elliott, pr\u00e9sident du West Coast Soaring Club, \u00e0 gauche, et Bill Nikolai, \u00e0 droite.<\/center><\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_section et_pb_section_0 et_section_regular\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_row et_pb_row_0 et_pb_row_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div> Instructeur de l&rsquo;ann\u00e9e Dave Underwood (\u00e0 gauche) et Randy Rauck (\u00e0 droite), instructeur HG et propri\u00e9taire du Freedom Flight Park \u00e0 Lumby, en Colombie-Britannique. Prix Solid Ground Jerry Mason pour son travail sur les implications des drones pour le sport Le laur\u00e9at Jerry Mason au centre, avec Edmond Rivere \u00e0 gauche et Norm Krcmar, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24,27],"tags":[],"class_list":["post-5359","post","type-post","status-publish","format-standard","hentry","category-le-lancement","category-prix"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2021 r\u00e9compenses pour les pilotes &quot;sp\u00e9ciaux - HPAC.ca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2021 r\u00e9compenses pour les pilotes &quot;sp\u00e9ciaux - HPAC.ca\" \/>\n<meta property=\"og:description\" content=\"Instructeur de l&#039;ann\u00e9e Dave Underwood (\u00e0 gauche) et Randy Rauck (\u00e0 droite), instructeur HG et propri\u00e9taire du Freedom Flight Park \u00e0 Lumby, en Colombie-Britannique. Prix Solid Ground Jerry Mason pour son travail sur les implications des drones pour le sport Le laur\u00e9at Jerry Mason au centre, avec Edmond Rivere \u00e0 gauche et Norm Krcmar, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/\" \/>\n<meta property=\"og:site_name\" content=\"HPAC.ca\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-30T20:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T12:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg\" \/>\n<meta name=\"author\" content=\"Tyler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tyler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/\"},\"author\":{\"name\":\"Tyler\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"headline\":\"2021 r\u00e9compenses pour les pilotes \u00ab\u00a0sp\u00e9ciaux\",\"datePublished\":\"2021-05-30T20:38:00+00:00\",\"dateModified\":\"2026-03-11T12:36:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/\"},\"wordCount\":127,\"image\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/2024.hpac.ca\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Instructor-of-the-year-Underwood.jpg\",\"articleSection\":[\"Le lancement\",\"Prix\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/\",\"url\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/\",\"name\":\"2021 r\u00e9compenses pour les pilotes \\\"sp\u00e9ciaux - HPAC.ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/2024.hpac.ca\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Instructor-of-the-year-Underwood.jpg\",\"datePublished\":\"2021-05-30T20:38:00+00:00\",\"dateModified\":\"2026-03-11T12:36:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/2024.hpac.ca\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Instructor-of-the-year-Underwood.jpg\",\"contentUrl\":\"https:\\\/\\\/2024.hpac.ca\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Instructor-of-the-year-Underwood.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2021\\\/05\\\/30\\\/2021-recompenses-pour-les-pilotes-speciaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021 r\u00e9compenses pour les pilotes \u00ab\u00a0sp\u00e9ciaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\",\"url\":\"https:\\\/\\\/3.97.40.4:443\\\/\",\"name\":\"HPAC.ca\",\"description\":\"Hang Gliding and Paragliding Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/3.97.40.4:443\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\",\"name\":\"Tyler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"caption\":\"Tyler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021 r\u00e9compenses pour les pilotes \"sp\u00e9ciaux - HPAC.ca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/","og_locale":"fr_FR","og_type":"article","og_title":"2021 r\u00e9compenses pour les pilotes \"sp\u00e9ciaux - HPAC.ca","og_description":"Instructeur de l'ann\u00e9e Dave Underwood (\u00e0 gauche) et Randy Rauck (\u00e0 droite), instructeur HG et propri\u00e9taire du Freedom Flight Park \u00e0 Lumby, en Colombie-Britannique. Prix Solid Ground Jerry Mason pour son travail sur les implications des drones pour le sport Le laur\u00e9at Jerry Mason au centre, avec Edmond Rivere \u00e0 gauche et Norm Krcmar, [&hellip;]","og_url":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/","og_site_name":"HPAC.ca","article_published_time":"2021-05-30T20:38:00+00:00","article_modified_time":"2026-03-11T12:36:42+00:00","og_image":[{"url":"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg","type":"","width":"","height":""}],"author":"Tyler","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Tyler","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#article","isPartOf":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/"},"author":{"name":"Tyler","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"headline":"2021 r\u00e9compenses pour les pilotes \u00ab\u00a0sp\u00e9ciaux","datePublished":"2021-05-30T20:38:00+00:00","dateModified":"2026-03-11T12:36:42+00:00","mainEntityOfPage":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/"},"wordCount":127,"image":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#primaryimage"},"thumbnailUrl":"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg","articleSection":["Le lancement","Prix"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/","url":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/","name":"2021 r\u00e9compenses pour les pilotes \"sp\u00e9ciaux - HPAC.ca","isPartOf":{"@id":"https:\/\/3.97.40.4:443\/#website"},"primaryImageOfPage":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#primaryimage"},"image":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#primaryimage"},"thumbnailUrl":"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg","datePublished":"2021-05-30T20:38:00+00:00","dateModified":"2026-03-11T12:36:42+00:00","author":{"@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"breadcrumb":{"@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#primaryimage","url":"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg","contentUrl":"https:\/\/2024.hpac.ca\/wp-content\/uploads\/2021\/05\/Instructor-of-the-year-Underwood.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/2024.hpac.ca\/fr\/2021\/05\/30\/2021-recompenses-pour-les-pilotes-speciaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/2024.hpac.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"2021 r\u00e9compenses pour les pilotes \u00ab\u00a0sp\u00e9ciaux"}]},{"@type":"WebSite","@id":"https:\/\/3.97.40.4:443\/#website","url":"https:\/\/3.97.40.4:443\/","name":"HPAC.ca","description":"Hang Gliding and Paragliding Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.97.40.4:443\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015","name":"Tyler","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","caption":"Tyler"}}]}},"_links":{"self":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/comments?post=5359"}],"version-history":[{"count":3,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5359\/revisions"}],"predecessor-version":[{"id":5393,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5359\/revisions\/5393"}],"wp:attachment":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/media?parent=5359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/categories?post=5359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/tags?post=5359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}