{"id":5402,"date":"2020-11-30T23:22:32","date_gmt":"2020-11-30T23:22:32","guid":{"rendered":"https:\/\/2024.hpac.ca\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/"},"modified":"2026-03-11T13:20:34","modified_gmt":"2026-03-11T13:20:34","slug":"interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre","status":"publish","type":"post","link":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/","title":{"rendered":"Interactions entre les deltaplanes et les parapentes et la faune terrestre"},"content":{"rendered":"\n<p>Brett Yeates, pilote de parapente de longue date \u00e0 Cranbrook, en Colombie-Britannique, m\u00e8ne une enqu\u00eate informelle dans le monde entier sur les rencontres des pilotes avec la faune terrestre et sur les \u00e9tudes formelles qui pourraient exister sur ce sujet, en particulier sur les ongul\u00e9s.  <\/p>\n\n<!--more-->\n\n<p>Il a pos\u00e9 sa question sur le <a href=\"https:\/\/www.paraglidingforum.com\/viewtopic.php?t=102259\">forum Paragliding<\/a> (section g\u00e9n\u00e9rale) et sur la page <a href=\"https:\/\/www.facebook.com\/groups\/HPAC.ACVL.MEMBERS\/\">Facebook de la HPAC<\/a>. N&rsquo;h\u00e9sitez pas \u00e0 nous faire part de vos exp\u00e9riences, car HPAC\/ACVL esp\u00e8re \u00e9laborer un document sur ce sujet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brett Yeates, pilote de parapente de longue date \u00e0 Cranbrook, en Colombie-Britannique, m\u00e8ne une enqu\u00eate informelle dans le monde entier sur les rencontres des pilotes avec la faune terrestre et sur les \u00e9tudes formelles qui pourraient exister sur ce sujet, en particulier sur les ongul\u00e9s.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24,15],"tags":[],"class_list":["post-5402","post","type-post","status-publish","format-standard","hentry","category-le-lancement","category-non-categorise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca\" \/>\n<meta property=\"og:description\" content=\"Brett Yeates, pilote de parapente de longue date \u00e0 Cranbrook, en Colombie-Britannique, m\u00e8ne une enqu\u00eate informelle dans le monde entier sur les rencontres des pilotes avec la faune terrestre et sur les \u00e9tudes formelles qui pourraient exister sur ce sujet, en particulier sur les ongul\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/\" \/>\n<meta property=\"og:site_name\" content=\"HPAC.ca\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-30T23:22:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T13:20:34+00:00\" \/>\n<meta name=\"author\" content=\"Tyler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tyler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/\"},\"author\":{\"name\":\"Tyler\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"headline\":\"Interactions entre les deltaplanes et les parapentes et la faune terrestre\",\"datePublished\":\"2020-11-30T23:22:32+00:00\",\"dateModified\":\"2026-03-11T13:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/\"},\"wordCount\":101,\"commentCount\":0,\"articleSection\":[\"Le lancement\",\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/\",\"url\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/\",\"name\":\"Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\"},\"datePublished\":\"2020-11-30T23:22:32+00:00\",\"dateModified\":\"2026-03-11T13:20:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2020\\\/11\\\/30\\\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interactions entre les deltaplanes et les parapentes et la faune terrestre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\",\"url\":\"https:\\\/\\\/3.97.40.4:443\\\/\",\"name\":\"HPAC.ca\",\"description\":\"Hang Gliding and Paragliding Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/3.97.40.4:443\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\",\"name\":\"Tyler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"caption\":\"Tyler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/","og_locale":"fr_FR","og_type":"article","og_title":"Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca","og_description":"Brett Yeates, pilote de parapente de longue date \u00e0 Cranbrook, en Colombie-Britannique, m\u00e8ne une enqu\u00eate informelle dans le monde entier sur les rencontres des pilotes avec la faune terrestre et sur les \u00e9tudes formelles qui pourraient exister sur ce sujet, en particulier sur les ongul\u00e9s.","og_url":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/","og_site_name":"HPAC.ca","article_published_time":"2020-11-30T23:22:32+00:00","article_modified_time":"2026-03-11T13:20:34+00:00","author":"Tyler","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Tyler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/#article","isPartOf":{"@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/"},"author":{"name":"Tyler","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"headline":"Interactions entre les deltaplanes et les parapentes et la faune terrestre","datePublished":"2020-11-30T23:22:32+00:00","dateModified":"2026-03-11T13:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/"},"wordCount":101,"commentCount":0,"articleSection":["Le lancement","Non cat\u00e9goris\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/","url":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/","name":"Interactions entre les deltaplanes et les parapentes et la faune terrestre - HPAC.ca","isPartOf":{"@id":"https:\/\/3.97.40.4:443\/#website"},"datePublished":"2020-11-30T23:22:32+00:00","dateModified":"2026-03-11T13:20:34+00:00","author":{"@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"breadcrumb":{"@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/2024.hpac.ca\/fr\/2020\/11\/30\/interactions-entre-les-deltaplanes-et-les-parapentes-et-la-faune-terrestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/2024.hpac.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Interactions entre les deltaplanes et les parapentes et la faune terrestre"}]},{"@type":"WebSite","@id":"https:\/\/3.97.40.4:443\/#website","url":"https:\/\/3.97.40.4:443\/","name":"HPAC.ca","description":"Hang Gliding and Paragliding Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.97.40.4:443\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015","name":"Tyler","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","caption":"Tyler"}}]}},"_links":{"self":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/comments?post=5402"}],"version-history":[{"count":1,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5402\/revisions"}],"predecessor-version":[{"id":5404,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5402\/revisions\/5404"}],"wp:attachment":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/media?parent=5402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/categories?post=5402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/tags?post=5402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}