{"id":5423,"date":"2014-10-03T15:07:27","date_gmt":"2014-10-03T15:07:27","guid":{"rendered":"https:\/\/2024.hpac.ca\/2014\/10\/03\/message-du-president\/"},"modified":"2014-10-03T15:07:27","modified_gmt":"2014-10-03T15:07:27","slug":"message-du-president","status":"publish","type":"post","link":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/","title":{"rendered":"Message du Pr\u00e9sident"},"content":{"rendered":"<h5 class=\"null\">Par Dom Juretic<\/h5>\n<p>Bonjour chers pilotes et amis du vol libre,<\/p>\n<p>Il se passe beaucoup de choses \u00e0 la HPAC et c&rsquo;est l&rsquo;une des raisons pour lesquelles notre AGA et le pr\u00e9sent bulletin sont un peu d\u00e9cal\u00e9s par rapport \u00e0 notre calendrier habituel.<\/p>\n<p>Suite aux changements majeurs apport\u00e9s \u00e0 la Loi canadienne sur les organisations \u00e0 but non lucratif, la PCSA doit demander \u00e0 Industrie Canada un certificat de continuation qui doit \u00eatre pr\u00e9sent\u00e9 par votre conseil d&rsquo;administration et autoris\u00e9 par une r\u00e9solution sp\u00e9ciale que vous avez approuv\u00e9e lors de notre AGA en ligne. Il ne s&rsquo;agissait pas d&rsquo;une proc\u00e9dure facultative, ce qui signifie simplement que l&rsquo;APHP devait demander et se conformer \u00e0 ces nouveaux r\u00e8glements pour continuer \u00e0 exister en tant qu&rsquo;association \u00e0 but non lucratif. <\/p>\n<p>Apr\u00e8s les nombreux changements d\u00e9j\u00e0 adopt\u00e9s dans notre syst\u00e8me d&rsquo;instruction, nous nous attaquons maintenant aux derniers \u00e9l\u00e9ments vis\u00e9s par cette r\u00e9vision majeure. Nous avons revu nos exigences en mati\u00e8re de qualification d&rsquo;instructeur et, enfin, nos exigences en mati\u00e8re d&rsquo;instructeur tandem. L&rsquo;examen de ces exigences \u00e9tait d\u00e9j\u00e0 programm\u00e9, car cette r\u00e9vision planifi\u00e9e avait commenc\u00e9 fin 2011 et devait \u00eatre globale. La r\u00e9vision \u00e9tait en cours lorsque la mort tragique de Lenami Godinez est survenue en Colombie-Britannique en avril 2012.   <\/p>\n<p>La HPAC est actuellement impliqu\u00e9e dans un litige en Colombie-Britannique concernant cet accident tragique et, \u00e0 ce titre, aucun autre commentaire ne peut \u00eatre fait tant que les tribunaux sont saisis de l&rsquo;affaire.<\/p>\n<p>Apr\u00e8s l&rsquo;accident, nous avons demand\u00e9 \u00e0 Martin Henry, ancien pr\u00e9sident de la HPAC et pilote de longue date, de lancer une enqu\u00eate officielle pour la HPAC. Le rapport qui a suivi a \u00e9galement \u00e9t\u00e9 utilis\u00e9 dans l&rsquo;affaire p\u00e9nale qui a reconnu l&rsquo;instructeur de tandem coupable de n\u00e9gligence criminelle ayant caus\u00e9 la mort. Le rapport est \u00e9vident et nous soutenons clairement ses recommandations. Ces recommandations sont actuellement examin\u00e9es par notre Conseil des instructeurs principaux (CSI) qui \u00e9tudiera les moyens les plus pratiques de les mettre en \u0153uvre. Les pilotes de tandem actuels seront \u00e9galement consult\u00e9s afin d&rsquo;obtenir leur avis et le comit\u00e9 de s\u00e9curit\u00e9 de la HPAC, compos\u00e9 de Suzanne Francoeur et de George Martin, sera charg\u00e9 de la supervision.    <\/p>\n<p>Tout cela pour vous encourager, en tant que membres, \u00e0 toujours donner la priorit\u00e9 \u00e0 la s\u00e9curit\u00e9.<\/p>\n<p>Parfois, lorsque vous faites quelque chose assez longtemps, cela devient automatique, normal. Nous, les pilotes, avons le sentiment d&rsquo;avoir droit \u00e0 ce grand ciel qui tourne au-dessus de nous. N&rsquo;oublions pas que lorsque nous sommes l\u00e0, c&rsquo;est parce que nous avons appris le langage du vent. Nous n&rsquo;en restons pas moins des \u00e9trangers dans ce royaume, au mieux des invit\u00e9s temporaires. Gardons cela \u00e0 l&rsquo;esprit lorsque nous acceptons tout ce qui peut nous aider \u00e0 profiter d&rsquo;une journ\u00e9e de plus \u00e0 faire ce que nous d\u00e9sirons si ardemment.    <\/p>\n<p>Nous vous souhaitons une bonne fin de saison de vol en toute s\u00e9curit\u00e9 !<\/p>\n<p>Domagoj Juretic<br \/>\nPr\u00e9sident de l&rsquo;HPAC<br \/>\nDirecteur r\u00e9gional pour le Qu\u00e9bec<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Dom Juretic Bonjour chers pilotes et amis du vol libre, Il se passe beaucoup de choses \u00e0 la HPAC et c&rsquo;est l&rsquo;une des raisons pour lesquelles notre AGA et le pr\u00e9sent bulletin sont un peu d\u00e9cal\u00e9s par rapport \u00e0 notre calendrier habituel. Suite aux changements majeurs apport\u00e9s \u00e0 la Loi canadienne sur les organisations [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-5423","post","type-post","status-publish","format-standard","hentry","category-le-lancement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.\" \/>\n<meta property=\"og:description\" content=\"Par Dom Juretic Bonjour chers pilotes et amis du vol libre, Il se passe beaucoup de choses \u00e0 la HPAC et c&rsquo;est l&rsquo;une des raisons pour lesquelles notre AGA et le pr\u00e9sent bulletin sont un peu d\u00e9cal\u00e9s par rapport \u00e0 notre calendrier habituel. Suite aux changements majeurs apport\u00e9s \u00e0 la Loi canadienne sur les organisations [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/\" \/>\n<meta property=\"og:site_name\" content=\"HPAC.ca\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-03T15:07:27+00:00\" \/>\n<meta name=\"author\" content=\"Tyler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tyler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/\"},\"author\":{\"name\":\"Tyler\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"headline\":\"Message du Pr\u00e9sident\",\"datePublished\":\"2014-10-03T15:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/\"},\"wordCount\":534,\"commentCount\":0,\"articleSection\":[\"Le lancement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/\",\"url\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/\",\"name\":\"Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\"},\"datePublished\":\"2014-10-03T15:07:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/2014\\\/10\\\/03\\\/message-du-president\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/2024.hpac.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Message du Pr\u00e9sident\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#website\",\"url\":\"https:\\\/\\\/3.97.40.4:443\\\/\",\"name\":\"HPAC.ca\",\"description\":\"Hang Gliding and Paragliding Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/3.97.40.4:443\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/3.97.40.4:443\\\/#\\\/schema\\\/person\\\/e62f32dd979a2dec8a6c6255c64f6015\",\"name\":\"Tyler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g\",\"caption\":\"Tyler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/","og_locale":"fr_FR","og_type":"article","og_title":"Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.","og_description":"Par Dom Juretic Bonjour chers pilotes et amis du vol libre, Il se passe beaucoup de choses \u00e0 la HPAC et c&rsquo;est l&rsquo;une des raisons pour lesquelles notre AGA et le pr\u00e9sent bulletin sont un peu d\u00e9cal\u00e9s par rapport \u00e0 notre calendrier habituel. Suite aux changements majeurs apport\u00e9s \u00e0 la Loi canadienne sur les organisations [&hellip;]","og_url":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/","og_site_name":"HPAC.ca","article_published_time":"2014-10-03T15:07:27+00:00","author":"Tyler","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Tyler","Dur\u00e9e de lecture estim\u00e9e":"3 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/#article","isPartOf":{"@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/"},"author":{"name":"Tyler","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"headline":"Message du Pr\u00e9sident","datePublished":"2014-10-03T15:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/"},"wordCount":534,"commentCount":0,"articleSection":["Le lancement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/","url":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/","name":"Message du Pr\u00e9sident - 10-03-2014-HPAC.ca%%.","isPartOf":{"@id":"https:\/\/3.97.40.4:443\/#website"},"datePublished":"2014-10-03T15:07:27+00:00","author":{"@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015"},"breadcrumb":{"@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/2024.hpac.ca\/fr\/2014\/10\/03\/message-du-president\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/2024.hpac.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Message du Pr\u00e9sident"}]},{"@type":"WebSite","@id":"https:\/\/3.97.40.4:443\/#website","url":"https:\/\/3.97.40.4:443\/","name":"HPAC.ca","description":"Hang Gliding and Paragliding Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.97.40.4:443\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/3.97.40.4:443\/#\/schema\/person\/e62f32dd979a2dec8a6c6255c64f6015","name":"Tyler","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/128d2a0e8278f96c13182e21d6dcfef928d0b86fdc7daee827d1e61c2973bd75?s=96&d=mm&r=g","caption":"Tyler"}}]}},"_links":{"self":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/comments?post=5423"}],"version-history":[{"count":0,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/posts\/5423\/revisions"}],"wp:attachment":[{"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/media?parent=5423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/categories?post=5423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2024.hpac.ca\/fr\/wp-json\/wp\/v2\/tags?post=5423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}